{"id":10129,"date":"2025-12-10T10:35:38","date_gmt":"2025-12-10T13:35:38","guid":{"rendered":"https:\/\/tnh1.audiencelabs.com.br\/?p=10129"},"modified":"2025-12-10T17:48:50","modified_gmt":"2025-12-10T20:48:50","slug":"sp-avalia-proibir-corridas-de-moto-por-app-em-dias-de-chuva","status":"publish","type":"post","link":"https:\/\/tnh1.audiencelabs.com.br\/sp-avalia-proibir-corridas-de-moto-por-app-em-dias-de-chuva\/","title":{"rendered":"Se esta lei for aprovada, servi\u00e7o de corrida por aplicativo ser\u00e1 proibido quando estiver chovendo"},"content":{"rendered":"\n<p>A <strong>C\u00e2mara Municipal de S\u00e3o Paulo (CMSP) discute um projeto de lei que prop\u00f5e endurecer as regras para o servi\u00e7o de corridas por aplicativo com motos<\/strong>, o chamado \u201cmoto-app\u201d. Entre as regras previstas est\u00e1 a <strong>proibi\u00e7\u00e3o de opera\u00e7\u00f5es em dias de chuva, vendavais ou condi\u00e7\u00f5es meteorol\u00f3gicas adversas.<\/strong><\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>O que diz o projeto<\/strong><\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>O texto aprovado em primeiro turno prev\u00ea <strong>restri\u00e7\u00f5es ao uso de motocicletas para transporte de passageiros em dias de \u201ctempestade, enchente ou baixa visibilidade\u201d.<\/strong><strong><br><\/strong><\/li>\n\n\n\n<li>Al\u00e9m disso, o projeto estabelece crit\u00e9rios t\u00e9cnicos rigorosos para ve\u00edculos e condutores:<strong> moto com at\u00e9 8 anos de fabrica\u00e7\u00e3o, placa na categoria aluguel (vermelha), capacete em bom estado, dispositivos de seguran\u00e7a adicionais, seguro obrigat\u00f3rio, exame toxicol\u00f3gico, entre outras exig\u00eancias.<\/strong><strong><br><\/strong><\/li>\n\n\n\n<li><strong>A lei tamb\u00e9m inclui proibi\u00e7\u00f5es para circula\u00e7\u00e3o em determinadas vias, como corredores de \u00f4nibus, vias r\u00e1pidas e faixas exclusivas<\/strong>, e em momentos de \u201ceventos adversos\u201d, o que abrange, segundo a proposta, chuvas fortes.<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Por que a medida est\u00e1 sendo proposta<\/strong><\/h3>\n\n\n<style>@media (min-width: 992px) {\n    .recomendadorV2Area1 {\n        width: 280px;\n    }\n    .recomendadorV2Area2 {\n        padding: 0px 20px;\n        width: calc(100% - 280px);\n    }\n}\n\n@media (max-width: 992px) {\n    .recomendadorV2Button {\n        margin: 0 auto;\n    }\n    .recomendadorV2Area {\n        flex-direction: column;\n        text-align: center;\n    }\n    .recomendadorV2Area2 {\n        padding: 0px 20px;\n    }\n}\n\n.recomendadorV2Area {\n    background: #eeeeee3d;\n    border-radius: 10px;\n    padding: 15px;\n    display: flex;\n    margin: 15px auto;\n    border: 1px solid #00000014;\n    max-width: 800px;\n}\n\n.recomendadorV2Area1 img {\n    width: 280px;\n    height: auto;\n    border-radius: 8px;\n}\n\n.linkrecomendadorv2 {\n    text-decoration: none !important;\n}\n\n.recomendadorV2Area2 .recomendadorV2Type {\n    text-transform: uppercase;\n    font-weight: 500;\n    font-size: 11px;\n    letter-spacing: 2px;\n    color: #666;\n    margin: 12px 0;\n    display: block;\n}\n\n.recomendadorV2Title h2 {\n    padding-top: 0px !important;\n    margin: 0px !important;\n    border-left: none !important;\n    padding-left: 0px !important;\n    line-height: 1.3;\n    color: #000 !important;\n    font-size: 24px;\n    margin-bottom: 12px !important;\n}\n\n.recomendadorV2Desc {\n    color: #333;\n    margin: 12px 0px !important;\n    font-size: 15px;\n    line-height: 1.5;\n}\n\n.recomendadorV2Button {\n    width: auto;\n    max-width: 200px;\n    margin: 0;\n    display: inline-flex;\n    align-items: center;\n    background: #1D3557;\n    border-radius: 8px;\n    color: #fff;\n    height: 36px;\n    justify-content: center;\n    text-align: center;\n    font-size: 14px;\n    padding: 0 20px;\n    transition: background-color 0.2s ease;\n}\n\n.recomendadorV2Button:hover {\n    background: #2a4d7a;\n}\n\n.recomendadorV2Button:after {\n    margin-top: -2px;\n    content: \"\u2192\";\n    padding: 0px 0px 0px 8px;\n}\n\n.recomendadorV2Alert {\n    text-align: left;\n    font-size: 11px;\n    margin-top: 8px;\n    color: #666;\n}\n\n.recomendadorFixedArea {\n    width: 100%;\n    display: flex;\n    justify-content: center;\n    align-items: center;\n}\n\n@media (min-width: 992px) {\n    #recomendadorFixed {\n        width: 32% !important;\n        left: 5%;\n    }\n    .recomendadorCloseFixed{\n        right: inherit !important;\n        left: 378px !important;\n    }\n}\n\n#recomendadorFixed {\n    width: 90%;\n    box-shadow: 0 10px 20px 0px #00000057;\n    display: none;\n    height: 90px;\n    background: #F6F6F6;\n    position: fixed;\n    flex-direction: row;\n    bottom: 10px;\n    z-index: 9999;\n    border-radius: 16px;\n    padding: 7px 10px;\n}\n\n.recomendadorLeftArea {\n    width: 160px;\n}\n\n.recomendadorRightArea h2 {\n    padding-top: 0px;\n    margin: 2px 0px 4px 0px !important;\n    font-weight: 400;\n    text-align: center;\n    padding-left: 0px !important;\n    color: #000 !important;\n    border-left: none !important;\n    line-height: 20px;\n    font-size: 12px !important;\n}\n\n.recomendadorImgFixed {\n    overflow: hidden;\n    padding: 8px 6px;\n    height: 100%;\n}\n\n.recomendadorImgFixed img {\n    height: 100% !important;\n    border-radius: 16px;\n}\n\n.recomendadorRightArea {\n    padding-top: 6px;\n    display: flex;\n    width: calc(100% - 130px);\n    justify-content: space-between;\n    align-items: center;\n    flex-direction: column;\n}\n\n.recomendadorButtonFixed {\n    margin: 0 auto;\n    background: #1D3557;\n    width: 80%;\n    text-align: center;\n    font-size: 10px;\n    color: #FFF;\n    padding: 2px 10px;\n    border-radius: 3px;\n}\n\n.recomendadorButtonFixed:after {\n    margin-top: -3px;\n    content: \"\u2192\";\n    padding: 0px 0px 0px 10px;\n}\n\n.recomendadorAlertFixed {\n    font-weight: 400;\n    text-align: center;\n    color: #484848;\n    font-size: 8px;\n}\n\n.recomendadorCloseFixed {\n    z-index: 99999;\n    display: none;\n    right: 0px;\n    left: inherit;\n    bottom: 99px;\n    position: fixed;\n    justify-content: center;\n    background: #F6F6F6;\n    width: 25px;\n    align-items: center;\n    height: 25px;\n    font-weight: 800;\n    border-radius: 50%;\n    border: 1px solid #EBEBEB;\n}\n\n.recomendadorV2Desc{\n    color: #000000;\n    margin: 20px 0px;\n}\n\n@media (max-width: 576px) {\n    .recomendadorV2Area {\n      padding: 10px;\n      max-width: 100%;\n    }\n  \n    .recomendadorV2Area1 img {\n      width: 100%;\n      border-radius: 6px;\n    }\n  \n    .recomendadorV2Area2 .recomendadorV2Type {\n      font-size: 9px;\n      letter-spacing: 1px;\n      margin: 8px 0;\n    }\n  \n    .recomendadorV2Title h2 {\n      font-size: 18px !important;\n      margin-bottom: 8px !important;\n      line-height: 1.2;\n    }\n  \n    .recomendadorV2Desc {\n      font-size: 14px;\n      margin: 8px 0 !important;\n      line-height: 1.4;\n    }\n  \n    .recomendadorV2Button {\n      font-size: 12px;\n      height: 30px;\n      padding: 0 12px;\n      max-width: 160px;\n    }\n  \n    .recomendadorV2Button:after {\n      padding-left: 6px;\n    }\n  }\n  <\/style>\n        <div class=\"lazyblock-recomendador-v2-2jDGz wp-block-lazyblock-recomendador-v2\">\n        <a class=\"linkrecomendadorv2\" href=\"https:\/\/www.tnh1.com.br\/variedades\/a-partir-do-dia-20-12-brasileiros-terao-que-pagar-nova-taxa-apenas-para-andar-de-carro\/?utm_source=lazy\" target=\"_blank\" rel=\"noopener\">\n            <div class=\"recomendadorV2Area\">\n            <div class=\"recomendadorV2Area1\">\n                <div class=\"recomendadorV2Img\">\n                <img class=\"lazyloaded\" decoding=\"async\" src=\"https:\/\/www.tnh1.com.br\/variedades\/wp-content\/uploads\/2025\/12\/A-partir-do-dia-2012-brasileiros-terao-que-pagar-nova-taxa-apenas-para-andar-de-carro-1140x570.jpg\" data-src=\"https:\/\/www.tnh1.com.br\/variedades\/wp-content\/uploads\/2025\/12\/A-partir-do-dia-2012-brasileiros-terao-que-pagar-nova-taxa-apenas-para-andar-de-carro-1140x570.jpg\" alt=\"\">\n                <\/div>\n            <\/div>\n            <div class=\"recomendadorV2Area2\">\n                <div class=\"recomendadorV2Type\">\n                    <span>Taxa Nova<\/span>\n                <\/div>\n                <div class=\"recomendadorV2Title\">\n                <h2><span>Cobran\u00e7a in\u00e9dita \ud83d\ude97<\/span><\/h2>\n                <\/div>\n                <div class=\"recomendadorV2Desc\">\n                <span>Veja quem pagar\u00e1 a nova tarifa<\/span>\n                <\/div>\n                <div class=\"recomendadorV2Button\">Entender regra<\/div>\n                <div class=\"recomendadorV2Alert\"><\/div>\n            <\/div>\n            <\/div>\n        <\/a>\n        <div>\n            <div style=\"z-index:99999;\" id=\"buttonClose\" onclick=\"closeRecomendadorFixed()\">\n            <div class=\"recomendadorCloseFixed\">X<\/div>\n            <\/div>\n            <a href=\"https:\/\/www.tnh1.com.br\/variedades\/a-partir-do-dia-20-12-brasileiros-terao-que-pagar-nova-taxa-apenas-para-andar-de-carro\/?utm_source=lazy\" target=\"_blank\" rel=\"noopener\">\n            <div class=\"recomendadorFixedArea\">\n                <div id=\"recomendadorFixed\">\n                <div class=\"recomendadorLeftArea\">\n                    <div class=\"recomendadorImgFixed\">\n                    <img class=\"lazyload\" decoding=\"async\" src=\"https:\/\/www.tnh1.com.br\/variedades\/wp-content\/uploads\/2025\/12\/A-partir-do-dia-2012-brasileiros-terao-que-pagar-nova-taxa-apenas-para-andar-de-carro-1140x570.jpg\" alt=\"\">\n                    <\/div>\n                <\/div>\n                <div class=\"recomendadorRightArea\">\n                    <div class=\"recomendadorTitleFixed\">\n                    <h2><span>Cobran\u00e7a in\u00e9dita \ud83d\ude97<\/span><\/h2>\n                    <\/div>\n                    <div class=\"recomendadorButtonFixed\">Entender regra<\/div>\n                    <div class=\"recomendadorAlertFixed\"><\/div>\n                <\/div>\n                <\/div>\n            <\/div>\n            <\/a>\n        <\/div>\n        <\/div>\n\n\n\n<p>A justificativa apresentada pelos defensores da lei \u00e9 o <strong>risco \u00e0 seguran\u00e7a dos passageiros e dos pr\u00f3prios motociclistas em condi\u00e7\u00f5es meteorol\u00f3gicas ruins.<\/strong> A chuva, combinada \u00e0 fragilidade de uma motocicleta em rela\u00e7\u00e3o a carro, aumentaria o perigo de acidentes, quedas e outros incidentes.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Cr\u00edticas e pol\u00eamica<\/strong><\/h3>\n\n\n\n<p>Por outro lado, entidades que representam as empresas de aplicativo de transporte, como <strong>Amobitec<\/strong>, j\u00e1 apontaram que <strong>o conjunto de restri\u00e7\u00f5es pode inviabilizar na pr\u00e1tica o servi\u00e7o de motoapp na capital.<\/strong> Para elas, a lei vai al\u00e9m de regras de seguran\u00e7a plaus\u00edveis e acaba por representar uma \u201cbarreira de entrada\u201d desproporcional.<\/p>\n\n\n\n<p>Al\u00e9m disso, h\u00e1 um hist\u00f3rico de disputas judiciais, <strong>decis\u00f5es recentes do Tribunal de Justi\u00e7a de S\u00e3o Paulo (TJ-SP)<\/strong> <strong>j\u00e1 declararam inconstitucional parte das proibi\u00e7\u00f5es municipais impostas ao servi\u00e7o de moto-aplicativo<\/strong>, por entenderem que a regulamenta\u00e7\u00e3o do transporte individual remunerado \u00e9 compet\u00eancia da Uni\u00e3o.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Situa\u00e7\u00e3o atual e pr\u00f3ximos passos<\/strong><\/h3>\n\n\n\n<p>Na vota\u00e7\u00e3o mais recente, <strong>a C\u00e2mara aprovou o projeto em segundo turno com 32 votos favor\u00e1veis, 16 contr\u00e1rios e uma absten\u00e7\u00e3o.<\/strong><\/p>\n\n\n\n<p>Com a aprova\u00e7\u00e3o, <strong>o texto ser\u00e1 encaminhado para san\u00e7\u00e3o do prefeito Ricardo Nunes. <\/strong>Caso sancionado, a lei poder\u00e1 instituir restri\u00e7\u00f5es para chuvas e condi\u00e7\u00f5es adversas.<a href=\"https:\/\/tmc.com.br\/brasil\/camara-municipal-aprova-projeto-que-regulamenta-moto-por-aplicativo-em-sao-paulo\/?utm_source=chatgpt.com\" target=\"_blank\" rel=\"noopener\">&nbsp;<\/a><\/p>\n\n\n\n<p>Se validada, essa mudan\u00e7a poder\u00e1 afetar fortemente o uso de motos por aplicativo na capital paulista, gerando incertezas para usu\u00e1rios, entregadores e para as pr\u00f3prias plataformas.<\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A C\u00e2mara Municipal de S\u00e3o Paulo (CMSP) discute um projeto de lei que prop\u00f5e endurecer as regras para o servi\u00e7o de corridas por aplicativo com motos, o chamado \u201cmoto-app\u201d. Entre as regras previstas est\u00e1 a proibi\u00e7\u00e3o de opera\u00e7\u00f5es em dias de chuva, vendavais ou condi\u00e7\u00f5es meteorol\u00f3gicas adversas. O que diz o projeto Por que a [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":10130,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jnews-multi-image_gallery":[],"jnews_single_post":{"format":"standard"},"jnews_primary_category":[],"jnews_social_meta":[],"jnews_post_split":[],"footnotes":""},"categories":[1],"tags":[1154,1153,887,150],"class_list":["post-10129","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-geral","tag-amobitec","tag-motocicleta","tag-mototaxi","tag-sao-paulo"],"_links":{"self":[{"href":"https:\/\/tnh1.audiencelabs.com.br\/wp-json\/wp\/v2\/posts\/10129","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tnh1.audiencelabs.com.br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tnh1.audiencelabs.com.br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tnh1.audiencelabs.com.br\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/tnh1.audiencelabs.com.br\/wp-json\/wp\/v2\/comments?post=10129"}],"version-history":[{"count":3,"href":"https:\/\/tnh1.audiencelabs.com.br\/wp-json\/wp\/v2\/posts\/10129\/revisions"}],"predecessor-version":[{"id":10219,"href":"https:\/\/tnh1.audiencelabs.com.br\/wp-json\/wp\/v2\/posts\/10129\/revisions\/10219"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tnh1.audiencelabs.com.br\/wp-json\/wp\/v2\/media\/10130"}],"wp:attachment":[{"href":"https:\/\/tnh1.audiencelabs.com.br\/wp-json\/wp\/v2\/media?parent=10129"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tnh1.audiencelabs.com.br\/wp-json\/wp\/v2\/categories?post=10129"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tnh1.audiencelabs.com.br\/wp-json\/wp\/v2\/tags?post=10129"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}