{"id":25366,"date":"2026-05-12T21:30:00","date_gmt":"2026-05-13T00:30:00","guid":{"rendered":"https:\/\/tnh1.audiencelabs.com.br\/?p=25366"},"modified":"2026-05-12T21:14:52","modified_gmt":"2026-05-13T00:14:52","slug":"aposentados-recebem-pessima-noticia-direto-do-stf-nesta-terca-feira-12-05","status":"publish","type":"post","link":"https:\/\/tnh1.audiencelabs.com.br\/aposentados-recebem-pessima-noticia-direto-do-stf-nesta-terca-feira-12-05\/","title":{"rendered":"Aposentados recebem p\u00e9ssima not\u00edcia direto do STF nesta ter\u00e7a-feira (12\/05)"},"content":{"rendered":"\n<p>O Supremo Tribunal Federal formou maioria para negar a chamada \u201crevis\u00e3o da vida toda\u201d a aposentados que ainda tinham a\u00e7\u00f5es em andamento na Justi\u00e7a. Na pr\u00e1tica, a decis\u00e3o reduz drasticamente as chances de segurados do INSS conseguirem aumentar o valor da aposentadoria com base em contribui\u00e7\u00f5es feitas antes de 1994.<\/p>\n\n\n\n<p>O julgamento foi suspenso ap\u00f3s pedido de destaque do ministro Edson Fachin, mas o placar de 7 votos a 1 j\u00e1 indica a tend\u00eancia da Corte.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">O que \u00e9 a revis\u00e3o da vida toda?<\/h2>\n\n\n\n<p>A revis\u00e3o da vida toda surgiu porque, ap\u00f3s o Plano Real, o INSS passou a considerar no c\u00e1lculo da aposentadoria apenas contribui\u00e7\u00f5es feitas a partir de julho de 1994. Isso prejudicou trabalhadores que recebiam sal\u00e1rios altos antes dessa data e tiveram renda menor depois.<\/p>\n\n\n\n<p>Na pr\u00e1tica, a revis\u00e3o permitia incluir sal\u00e1rios antigos no c\u00e1lculo do benef\u00edcio. Exemplo: Um trabalhador contribuiu com valores altos entre 1985 e 1993, mas passou a ganhar menos depois de 1994. Sem revis\u00e3o, o INSS ignorava os sal\u00e1rios antigos; Com a revis\u00e3o, esses valores entrariam na conta e a aposentadoria poderia aumentar.<\/p>\n\n\n\n<p>Em 2022, o STF havia reconhecido o direito \u00e0 revis\u00e3o. Por\u00e9m, em 2024, o tribunal mudou de entendimento e decidiu que a regra de transi\u00e7\u00e3o da Previd\u00eancia deve ser obrigat\u00f3ria.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">O que muda agora para aposentados?<\/h2>\n\n\n\n<p>O novo julgamento discute justamente quem entrou na Justi\u00e7a antes da mudan\u00e7a de posi\u00e7\u00e3o do STF. A maioria dos ministros entende que:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>quem j\u00e1 recebeu valores da revis\u00e3o n\u00e3o precisar\u00e1 devolver dinheiro;<\/li>\n\n\n\n<li>quem ainda tinha processo em andamento provavelmente perder\u00e1 o direito ao rec\u00e1lculo;<\/li>\n\n\n\n<li>novas a\u00e7\u00f5es judiciais sobre o tema tendem a n\u00e3o prosperar.<\/li>\n<\/ul>\n\n\n\n<p>O relator do caso, Kassio Nunes Marques, afirmou que o Supremo j\u00e1 rejeitou repetidamente a tese da revis\u00e3o. J\u00e1 o ministro Dias Toffoli divergiu e defendeu prote\u00e7\u00e3o aos aposentados que confiaram na decis\u00e3o anterior da Corte.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Supremo Tribunal Federal formou maioria para negar a chamada \u201crevis\u00e3o da vida toda\u201d a aposentados que ainda tinham a\u00e7\u00f5es em andamento na Justi\u00e7a. Na pr\u00e1tica, a decis\u00e3o reduz drasticamente as chances de segurados do INSS conseguirem aumentar o valor da aposentadoria com base em contribui\u00e7\u00f5es feitas antes de 1994. O julgamento foi suspenso ap\u00f3s [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":25367,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jnews-multi-image_gallery":[],"jnews_single_post":{"format":"standard"},"jnews_primary_category":[],"jnews_social_meta":[],"jnews_post_split":[],"footnotes":""},"categories":[1],"tags":[],"class_list":["post-25366","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-geral"],"_links":{"self":[{"href":"https:\/\/tnh1.audiencelabs.com.br\/wp-json\/wp\/v2\/posts\/25366","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tnh1.audiencelabs.com.br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tnh1.audiencelabs.com.br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tnh1.audiencelabs.com.br\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/tnh1.audiencelabs.com.br\/wp-json\/wp\/v2\/comments?post=25366"}],"version-history":[{"count":1,"href":"https:\/\/tnh1.audiencelabs.com.br\/wp-json\/wp\/v2\/posts\/25366\/revisions"}],"predecessor-version":[{"id":25368,"href":"https:\/\/tnh1.audiencelabs.com.br\/wp-json\/wp\/v2\/posts\/25366\/revisions\/25368"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tnh1.audiencelabs.com.br\/wp-json\/wp\/v2\/media\/25367"}],"wp:attachment":[{"href":"https:\/\/tnh1.audiencelabs.com.br\/wp-json\/wp\/v2\/media?parent=25366"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tnh1.audiencelabs.com.br\/wp-json\/wp\/v2\/categories?post=25366"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tnh1.audiencelabs.com.br\/wp-json\/wp\/v2\/tags?post=25366"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}