{"id":25393,"date":"2026-05-13T09:18:00","date_gmt":"2026-05-13T12:18:00","guid":{"rendered":"https:\/\/tnh1.audiencelabs.com.br\/?p=25393"},"modified":"2026-05-13T09:03:13","modified_gmt":"2026-05-13T12:03:13","slug":"nova-lei-pode-liberar-credito-para-a-compra-de-arma-de-fogo-no-brasil","status":"publish","type":"post","link":"https:\/\/tnh1.audiencelabs.com.br\/nova-lei-pode-liberar-credito-para-a-compra-de-arma-de-fogo-no-brasil\/","title":{"rendered":"Nova lei pode liberar cr\u00e9dito para a compra de arma de fogo no Brasil"},"content":{"rendered":"\n<p>No dia 12 de maio, a Comiss\u00e3o de Seguran\u00e7a P\u00fablica da C\u00e2mara dos Deputados aprovou uma proposta: a utiliza\u00e7\u00e3o do <strong>Fundo de Garantia por Tempo de Servi\u00e7o <\/strong>(FGTS) para a <strong>compra de armas de fogo.<\/strong> A medida causou debate imediato por alterar a finalidade original do FGTS.<\/p>\n\n\n\n<p>A sess\u00e3o foi realizada em Bras\u00edlia, e a proposta segue para outras comiss\u00f5es, incluindo as de Finan\u00e7as, Tributa\u00e7\u00e3o, Trabalho e Constitui\u00e7\u00e3o e Justi\u00e7a, antes de potencialmente ser discutida pelo Senado, salvo algum recurso que altere o caminho legislativo.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Detalhes da proposta<\/h2>\n\n\n\n<p>Idealizada pelo deputado Marcos Pollon (PL-MS), a proposta autoriza que trabalhadores saquem parte do FGTS anualmente no seu anivers\u00e1rio para a aquisi\u00e7\u00e3o de armas de fogo.<\/p>\n\n\n\n<p>O procedimento exige a apresenta\u00e7\u00e3o de documentos espec\u00edficos, como a autoriza\u00e7\u00e3o de compra de arma e a comprova\u00e7\u00e3o de regularidade no Sistema Nacional de Armas (SINARM) ou no Sistema de Gerenciamento Militar de Armas (SIGMA).<\/p>\n\n\n\n<p>Al\u00e9m disso, o valor liberado para saque deve cobrir custos referentes \u00e0 arma, muni\u00e7\u00e3o e acess\u00f3rios essenciais \u00e0 seguran\u00e7a pessoal. A legisla\u00e7\u00e3o atual requer comprova\u00e7\u00e3o de capacidade t\u00e9cnica e psicol\u00f3gica, assim como a inexist\u00eancia de antecedentes criminais.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Debate&nbsp;<\/h2>\n\n\n\n<p>O FGTS foi institu\u00eddo para proteger trabalhadores em situa\u00e7\u00f5es como <strong>demiss\u00e3o sem justa causa, aposentadoria<\/strong> e <strong>aquisi\u00e7\u00e3o de im\u00f3vel. <\/strong>A possibilidade de utilizar esses recursos para a compra de armamentos gerou divis\u00f5es.<\/p>\n\n\n\n<p>Cr\u00edticos afirmam que tal uso desvia da prote\u00e7\u00e3o social para a qual o FGTS foi criado.<\/p>\n\n\n\n<p>Defensores do projeto argumentam que a medida pode democratizar o acesso legal \u00e0s armas, especialmente para cidad\u00e3os de baixa renda. Eles destacam que o custo elevado para a aquisi\u00e7\u00e3o formal de armamentos seria um obst\u00e1culo s\u00e9rio.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Comiss\u00e3o de Seguran\u00e7a P\u00fablica da C\u00e2mara dos Deputados aprovou proposta que pode facilitar a compra de armas de fogo. <\/p>\n","protected":false},"author":8,"featured_media":25394,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jnews-multi-image_gallery":[],"jnews_single_post":{"format":"standard"},"jnews_primary_category":[],"jnews_social_meta":[],"jnews_post_split":[],"footnotes":""},"categories":[1],"tags":[],"class_list":["post-25393","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-geral"],"_links":{"self":[{"href":"https:\/\/tnh1.audiencelabs.com.br\/wp-json\/wp\/v2\/posts\/25393","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tnh1.audiencelabs.com.br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tnh1.audiencelabs.com.br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tnh1.audiencelabs.com.br\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/tnh1.audiencelabs.com.br\/wp-json\/wp\/v2\/comments?post=25393"}],"version-history":[{"count":2,"href":"https:\/\/tnh1.audiencelabs.com.br\/wp-json\/wp\/v2\/posts\/25393\/revisions"}],"predecessor-version":[{"id":25396,"href":"https:\/\/tnh1.audiencelabs.com.br\/wp-json\/wp\/v2\/posts\/25393\/revisions\/25396"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tnh1.audiencelabs.com.br\/wp-json\/wp\/v2\/media\/25394"}],"wp:attachment":[{"href":"https:\/\/tnh1.audiencelabs.com.br\/wp-json\/wp\/v2\/media?parent=25393"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tnh1.audiencelabs.com.br\/wp-json\/wp\/v2\/categories?post=25393"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tnh1.audiencelabs.com.br\/wp-json\/wp\/v2\/tags?post=25393"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}