{"id":25480,"date":"2026-05-13T14:28:24","date_gmt":"2026-05-13T17:28:24","guid":{"rendered":"https:\/\/tnh1.audiencelabs.com.br\/?p=25480"},"modified":"2026-05-13T14:28:30","modified_gmt":"2026-05-13T17:28:30","slug":"as-vesperas-da-convocacao-ancelotti-joga-tudo-no-ventilador-sobre-neymar","status":"publish","type":"post","link":"https:\/\/tnh1.audiencelabs.com.br\/as-vesperas-da-convocacao-ancelotti-joga-tudo-no-ventilador-sobre-neymar\/","title":{"rendered":"\u00c0s v\u00e9speras da convoca\u00e7\u00e3o, Ancelotti joga tudo no ventilador sobre Neymar"},"content":{"rendered":"\n<p>Na pr\u00f3xima segunda-feira, 18, \u00e0s 17h (de Bras\u00edlia), no Museu do Amanh\u00e3, no Rio de Janeiro, o t\u00e9cnico Carlo Ancelotti convocar\u00e1 os 26 jogadores que v\u00e3o disputar a Copa do Mundo de 2026 pela Sele\u00e7\u00e3o Brasileira. Diante disso, um debate permanece quente entre especialistas e torcedores: Neymar est\u00e1 ou n\u00e3o na lista final de convocados? Em entrevista \u00e0 ag\u00eancia Reuters, o treinador &#8220;jogou tudo no ventilador&#8221; sobre o que pensa em rela\u00e7\u00e3o ao atleta.<\/p>\n\n\n\n<p>Primeiramente, o italiano afirmou que acha normal os in\u00fameros pedidos pela convoca\u00e7\u00e3o do craque santista. Vale lembrar que Neymar ainda n\u00e3o foi chamado para a sele\u00e7\u00e3o na era Ancelotti. O comandante da Amarelinha disse que j\u00e1 notou que o jogador \u00e9 muito amado no pa\u00eds, tanto por torcedores quanto pelos pr\u00f3prios jogadores da sele\u00e7\u00e3o. Dessa forma, acredita que, ao chamar Neymar, n\u00e3o estar\u00e1 colocando uma &#8220;bomba&#8221; no vesti\u00e1rio.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Desempenho atual do atleta e press\u00e3o por convoca\u00e7\u00e3o<\/h2>\n\n\n\n<p>Ancelotti elogiou o desempenho atual do camisa 10 do Santos, que vem conseguindo ter uma sequ\u00eancia maior de partidas e participando de gols. No entanto, o treinador ressaltou que, apesar de ser uma decis\u00e3o dif\u00edcil, a convoca\u00e7\u00e3o ou n\u00e3o do atleta n\u00e3o \u00e9 algo que o deixe pressionado.<\/p>\n\n\n\n<p>O comandante afirmou que, na hora de decidir quem convocar, \u00e9 necess\u00e1rio levar em considera\u00e7\u00e3o diversos detalhes. Al\u00e9m disso, afirmou que Neymar \u00e9 um jogador importante para o pa\u00eds devido a todo o talento que demonstrou ao longo dos anos e que, mesmo ap\u00f3s uma les\u00e3o grave no joelho, vem trabalhando muito para recuperar seu alto n\u00edvel no futebol.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Impacto de Neymar em um ambiente de concentra\u00e7\u00e3o<\/h2>\n\n\n\n<p>Ao ser questionado sobre se o ambiente de concentra\u00e7\u00e3o da sele\u00e7\u00e3o poderia ser afetado com a presen\u00e7a do camisa 10, o italiano foi direto em sua resposta, afirmando que h\u00e1 total controle nesse quesito e que isso ser\u00e1 mantido at\u00e9 o final da Copa, com ou sem o jogador.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Na pr\u00f3xima segunda-feira, 18, \u00e0s 17h (de Bras\u00edlia), no Museu do Amanh\u00e3, no Rio de Janeiro, o t\u00e9cnico Carlo Ancelotti convocar\u00e1 os 26 jogadores que v\u00e3o disputar a Copa do Mundo de 2026 pela Sele\u00e7\u00e3o Brasileira. Diante disso, um debate permanece quente entre especialistas e torcedores: Neymar est\u00e1 ou n\u00e3o na lista final de convocados? [&hellip;]<\/p>\n","protected":false},"author":20,"featured_media":19876,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jnews-multi-image_gallery":[],"jnews_single_post":{"format":"standard"},"jnews_primary_category":[],"jnews_social_meta":[],"jnews_post_split":[],"footnotes":""},"categories":[1],"tags":[],"class_list":["post-25480","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-geral"],"_links":{"self":[{"href":"https:\/\/tnh1.audiencelabs.com.br\/wp-json\/wp\/v2\/posts\/25480","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tnh1.audiencelabs.com.br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tnh1.audiencelabs.com.br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tnh1.audiencelabs.com.br\/wp-json\/wp\/v2\/users\/20"}],"replies":[{"embeddable":true,"href":"https:\/\/tnh1.audiencelabs.com.br\/wp-json\/wp\/v2\/comments?post=25480"}],"version-history":[{"count":1,"href":"https:\/\/tnh1.audiencelabs.com.br\/wp-json\/wp\/v2\/posts\/25480\/revisions"}],"predecessor-version":[{"id":25483,"href":"https:\/\/tnh1.audiencelabs.com.br\/wp-json\/wp\/v2\/posts\/25480\/revisions\/25483"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tnh1.audiencelabs.com.br\/wp-json\/wp\/v2\/media\/19876"}],"wp:attachment":[{"href":"https:\/\/tnh1.audiencelabs.com.br\/wp-json\/wp\/v2\/media?parent=25480"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tnh1.audiencelabs.com.br\/wp-json\/wp\/v2\/categories?post=25480"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tnh1.audiencelabs.com.br\/wp-json\/wp\/v2\/tags?post=25480"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}