{"id":4439,"date":"2025-10-09T11:27:33","date_gmt":"2025-10-09T14:27:33","guid":{"rendered":"https:\/\/tnh1.audiencelabs.com.br\/?p=4439"},"modified":"2025-10-09T11:27:40","modified_gmt":"2025-10-09T14:27:40","slug":"respire-fundo-antes-de-ver-quanto-vale-a-mansao-de-vinicius-junior-que-pegou-fogo","status":"publish","type":"post","link":"https:\/\/tnh1.audiencelabs.com.br\/respire-fundo-antes-de-ver-quanto-vale-a-mansao-de-vinicius-junior-que-pegou-fogo\/","title":{"rendered":"Respire fundo antes de ver quanto vale a mans\u00e3o de Vin\u00edcius J\u00fanior que pegou fogo"},"content":{"rendered":"\n<p>Ap\u00f3s uma semana marcada por pol\u00eamicas, <strong>Vin\u00edcius J\u00fanior<\/strong> enfrentou um novo susto nesta quinta-feira (9), um princ\u00edpio de inc\u00eandio atingiu sua luxuosa mans\u00e3o em <strong>Alcobendas<\/strong>, regi\u00e3o nobre de <strong>Madri<\/strong>, na Espanha.&nbsp;<\/p>\n\n\n\n<p>De acordo com o canal <strong>Telemadrid<\/strong>, o fogo teve origem em uma falha el\u00e9trica no teto falso da sauna localizada no subsolo da resid\u00eancia. O <strong>Corpo de Bombeiros Comunit\u00e1rio de Madri<\/strong> foi acionado rapidamente e conseguiu controlar as chamas antes que o incidente tomasse maiores propor\u00e7\u00f5es.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Fogo controlado e ningu\u00e9m ferido<\/strong><\/h3>\n\n\n\n<p>Segundo o jornal espanhol <strong>Marca<\/strong>, duas equipes de bombeiros chegaram ao local por volta das 11h e atuaram para conter o inc\u00eandio e ventilar o im\u00f3vel, que ficou tomado pela fuma\u00e7a em dois andares. O subsolo, onde ficava a sauna, foi totalmente destru\u00eddo.&nbsp;<\/p>\n\n\n\n<p>Apesar do susto, <strong>ningu\u00e9m ficou ferido<\/strong>, j\u00e1 que o jogador est\u00e1 <strong>na Coreia do Sul<\/strong>, onde se prepara com a sele\u00e7\u00e3o brasileira para a partida desta sexta-feira (10). As autoridades espanholas ainda n\u00e3o divulgaram o levantamento completo dos danos.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>A mans\u00e3o milion\u00e1ria<\/strong><\/h3>\n\n\n\n<p>O im\u00f3vel de Vin\u00edcius J\u00fanior impressiona pelo luxo e pelas dimens\u00f5es. Avaliada em <strong>10 milh\u00f5es de euros<\/strong>, cerca de <strong>R$ 60 milh\u00f5es<\/strong>, a propriedade est\u00e1 entre as mais caras da regi\u00e3o de Alcobendas. Segundo o jornal brit\u00e2nico <strong>The Sun<\/strong>, o patrim\u00f4nio total do atleta chega a <strong>21 milh\u00f5es de euros<\/strong>.<\/p>\n\n\n\n<p>Com <strong>2.500 metros quadrados de \u00e1rea \u00fatil<\/strong>, a resid\u00eancia conta com <strong>seis quartos<\/strong>, <strong>seis banheiros<\/strong>, <strong>cinema particular<\/strong>, <strong>sala de jogos<\/strong>, <strong>bar<\/strong>, <strong>piscina<\/strong>, <strong>quadra de t\u00eanis<\/strong> e at\u00e9 um <strong>campo de futebol<\/strong>. O im\u00f3vel tamb\u00e9m abriga uma <strong>sauna seca e uma sauna a vapor<\/strong>, sistemas de automa\u00e7\u00e3o e seguran\u00e7a de ponta, al\u00e9m de um <strong>quarto do p\u00e2nico<\/strong> e <strong>elevador interno<\/strong>.<\/p>\n\n\n\n<p>O condom\u00ednio em que o craque mora re\u00fane <strong>campos de golfe<\/strong>, <strong>escolas particulares<\/strong> e fica a apenas <strong>15 minutos do centro de treinamento do Real Madrid<\/strong>, uma localiza\u00e7\u00e3o privilegiada que refor\u00e7a o estilo de vida luxuoso do atacante.<\/p>\n\n\n\n<p>Apesar do incidente, a estrutura da casa foi preservada, e os bombeiros conseguiram evitar danos maiores.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ap\u00f3s uma semana marcada por pol\u00eamicas, Vin\u00edcius J\u00fanior enfrentou um novo susto nesta quinta-feira (9), um princ\u00edpio de inc\u00eandio atingiu sua luxuosa mans\u00e3o em Alcobendas, regi\u00e3o nobre de Madri, na Espanha.&nbsp; De acordo com o canal Telemadrid, o fogo teve origem em uma falha el\u00e9trica no teto falso da sauna localizada no subsolo da resid\u00eancia. [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":4440,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jnews-multi-image_gallery":[],"jnews_single_post":{"format":"standard"},"jnews_primary_category":[],"jnews_social_meta":[],"jnews_post_split":[],"footnotes":""},"categories":[1],"tags":[316],"class_list":["post-4439","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-geral","tag-vini-jr"],"_links":{"self":[{"href":"https:\/\/tnh1.audiencelabs.com.br\/wp-json\/wp\/v2\/posts\/4439","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tnh1.audiencelabs.com.br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tnh1.audiencelabs.com.br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tnh1.audiencelabs.com.br\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/tnh1.audiencelabs.com.br\/wp-json\/wp\/v2\/comments?post=4439"}],"version-history":[{"count":1,"href":"https:\/\/tnh1.audiencelabs.com.br\/wp-json\/wp\/v2\/posts\/4439\/revisions"}],"predecessor-version":[{"id":4441,"href":"https:\/\/tnh1.audiencelabs.com.br\/wp-json\/wp\/v2\/posts\/4439\/revisions\/4441"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tnh1.audiencelabs.com.br\/wp-json\/wp\/v2\/media\/4440"}],"wp:attachment":[{"href":"https:\/\/tnh1.audiencelabs.com.br\/wp-json\/wp\/v2\/media?parent=4439"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tnh1.audiencelabs.com.br\/wp-json\/wp\/v2\/categories?post=4439"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tnh1.audiencelabs.com.br\/wp-json\/wp\/v2\/tags?post=4439"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}